

{"id":8531,"date":"2012-09-24T07:45:56","date_gmt":"2012-09-24T11:45:56","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=8531"},"modified":"2012-09-24T07:45:56","modified_gmt":"2012-09-24T11:45:56","slug":"una-casa-a-tono-con-la-primavera","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2012\/09\/24\/una-casa-a-tono-con-la-primavera\/","title":{"rendered":"Una casa a tono con la primavera"},"content":{"rendered":"<p>\u00bfQu\u00e9 les parece partir la primera semana de primavera con una casa alegre y colorida? A trav\u00e9s del blog <a href=\"http:\/\/thedesignfiles.net\/2012\/09\/melbourne-home-%C2%B7-katie-graham-and-family\/#more-46566\" target=\"_blank\">The Design Files<\/a>, encontr\u00e9 el hogar de Katie Graham en Melbourne. Katie es mam\u00e1 de 3 hijos y due\u00f1a de la tienda <a href=\"https:\/\/thefamilylovetree.com.au\/store\" target=\"_blank\">The Family Love Tree<\/a>. Su casa tiene muchas cosas de su tienda (como los respaldos de cama, cojines y quilts) y tambi\u00e9n varios muebles de estilo mid-century. Pero sin duda lo que se lleva todos los premios es la cocina amarilla, no creen? Que tengan buena semana!<\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-living2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8534\" title=\"Katie-living2\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-living2.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-living2.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-living2-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-dining.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8535\" title=\"Katie-dining\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-dining.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-dining.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-dining-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kitchen.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8533\" title=\"Katie-kitchen\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kitchen.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kitchen.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kitchen-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-masterbed.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8536\" title=\"Katie-masterbed\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-masterbed.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-masterbed.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-masterbed-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8538\" title=\"Katie-kids1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids1.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids1.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids1-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8537\" title=\"Katie-kids2\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids2.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids2.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-kids2-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-guest.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8539\" title=\"Katie-guest\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-guest.jpg\" alt=\"\" width=\"600\" height=\"840\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-guest.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/Katie-guest-357x500.jpg 357w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 les parece partir la primera semana de primavera con una casa alegre y colorida? A trav\u00e9s del blog The Design Files, encontr\u00e9 el hogar de Katie Graham en Melbourne. Katie es mam\u00e1 de 3 hijos y due\u00f1a de la tienda The Family Love Tree. Su casa tiene muchas cosas de su tienda (como los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/8531"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=8531"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/8531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/8541"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=8531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=8531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=8531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}