

{"id":8473,"date":"2012-09-21T10:03:56","date_gmt":"2012-09-21T14:03:56","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=8473"},"modified":"2012-09-21T11:28:02","modified_gmt":"2012-09-21T15:28:02","slug":"cubos-virtuales","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2012\/09\/21\/cubos-virtuales\/","title":{"rendered":"Cubos virtuales"},"content":{"rendered":"<p>En el primer a\u00f1o de Arquitectura\u00a0sufr\u00edamos\u00a0con los cubos <em>virtuales <\/em>donde teniamos que ver lo que nadie ve\u00eda<em>,<\/em> al menos yo no. Hoy me encuentro con estas mesas que trabajan el mismo concepto. \u00a0La\u00a0sustracci\u00f3n del cubo como forma terminada. (Lo virtual era el espacio que estaba pero que no estaba construido). En honor a esos a\u00f1os de sufrimiento pero que florecieron en una linda carrera, me gustar\u00eda poder adue\u00f1arme de una de estas mesas de OD Design donde la pureza de las l\u00edneas blancas hacen perfecto\u00a0juego con las tapas de madera y donde tu mesa puede cambiar de mil maneras. Para m\u00e1s s\u00edganme en <a href=\"http:\/\/www.specadoc.com\">Sin Pecado Concebida<\/a>.<a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8474\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg 1000w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666-500x333.jpeg 500w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666-600x400.jpeg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345239486-anetteb-ju-cafe-2-666x1000.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8477\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345239486-anetteb-ju-cafe-2-666x1000.jpeg\" alt=\"\" width=\"666\" height=\"1000\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345239486-anetteb-ju-cafe-2-666x1000.jpeg 666w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345239486-anetteb-ju-cafe-2-666x1000-333x500.jpeg 333w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238370-anetteb-ju-17-666x1000.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8476\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238370-anetteb-ju-17-666x1000.jpeg\" alt=\"\" width=\"666\" height=\"1000\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238370-anetteb-ju-17-666x1000.jpeg 666w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238370-anetteb-ju-17-666x1000-333x500.jpeg 333w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8475\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666.jpeg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666.jpeg 1000w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666-500x333.jpeg 500w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666-768x511.jpeg 768w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238293-anetteb-ju-16-1000x666-600x400.jpeg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8474\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666.jpeg 1000w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666-500x333.jpeg 500w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/09\/1345238249-anetteb-ju-6-1000x666-600x400.jpeg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el primer a\u00f1o de Arquitectura\u00a0sufr\u00edamos\u00a0con los cubos virtuales donde teniamos que ver lo que nadie ve\u00eda, al menos yo no. Hoy me encuentro con estas mesas que trabajan el mismo concepto. \u00a0La\u00a0sustracci\u00f3n del cubo como forma terminada. (Lo virtual era el espacio que estaba pero que no estaba construido). En honor a esos a\u00f1os&#8230;<\/p>\n","protected":false},"author":12,"featured_media":8475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[47,48,49],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/8473"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=8473"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/8473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/8475"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=8473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=8473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=8473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}