

{"id":5872,"date":"2012-04-20T12:56:32","date_gmt":"2012-04-20T12:56:32","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=5872"},"modified":"2012-04-20T12:56:32","modified_gmt":"2012-04-20T12:56:32","slug":"el-mejor-lugar-para-trabajar","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2012\/04\/20\/el-mejor-lugar-para-trabajar\/","title":{"rendered":"El mejor lugar para trabajar"},"content":{"rendered":"<p>Por fin es viernes! Pero si trabajara en estas oficinas me dar\u00eda lo mismo tener que ir el s\u00e1bado y el domingo. Aqu\u00ed definitivamente se respira un ambiente acogedor, con espacios\u00a0que invitan a reunirse a discutir ideas y proyectos. Un grupo de siete amigos comparten este loft en Los Angeles en donde la creatividad y el entusiasmo \u00a0se aprecian en cada rinc\u00f3n, no les parece?<\/p>\n<p>Pueden ver el tour completo en este <a href=\"http:\/\/www.apartmenttherapy.com\/a-creative-collective-in-atwater-village-workspace-tour-168585\" target=\"_blank\">link<\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0323_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5874\" title=\"IMG_0323_rect640\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0323_rect640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0323_rect640.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0323_rect640-500x333.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0376_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5877\" title=\"7\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0376_rect640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0376_rect640.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0376_rect640-500x333.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0387_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5880\" title=\"6\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0387_rect640.jpg\" alt=\"\" width=\"427\" height=\"640\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0387_rect640.jpg 427w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0387_rect640-333x500.jpg 333w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0395_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5881\" title=\"5\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0395_rect640.jpg\" alt=\"\" width=\"427\" height=\"640\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0395_rect640.jpg 427w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0395_rect640-333x500.jpg 333w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/bri_officetour-4.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5873\" title=\"5\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/bri_officetour-4.jpg\" alt=\"\" width=\"540\" height=\"810\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/bri_officetour-4.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/bri_officetour-4-333x500.jpg 333w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0614_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5882\" title=\"4\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0614_rect640.jpg\" alt=\"\" width=\"427\" height=\"640\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0614_rect640.jpg 427w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0614_rect640-333x500.jpg 333w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0355_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5875\" title=\"IMG_0355_rect640\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0355_rect640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0355_rect640.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0355_rect640-500x333.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0385_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5879\" title=\"1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0385_rect640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0385_rect640.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0385_rect640-500x333.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0384_rect640.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5878\" title=\"2\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0384_rect640.jpg\" alt=\"\" width=\"540\" height=\"360\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0384_rect640.jpg 540w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2012\/04\/IMG_0384_rect640-500x333.jpg 500w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por fin es viernes! Pero si trabajara en estas oficinas me dar\u00eda lo mismo tener que ir el s\u00e1bado y el domingo. Aqu\u00ed definitivamente se respira un ambiente acogedor, con espacios\u00a0que invitan a reunirse a discutir ideas y proyectos. Un grupo de siete amigos comparten este loft en Los Angeles en donde la creatividad y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[40,74],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/5872"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=5872"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/5872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/5877"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=5872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=5872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=5872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}