

{"id":421,"date":"2011-03-08T14:34:49","date_gmt":"2011-03-08T14:34:49","guid":{"rendered":"http:\/\/depto51.cl\/?p=421"},"modified":"2012-01-26T00:32:29","modified_gmt":"2012-01-26T00:32:29","slug":"banderines-2","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/","title":{"rendered":"Banderines"},"content":{"rendered":"<p>Los primeros banderines con los que me obsesion\u00e9 fueron con los de  papel picado mexicanos. Estos banderines se hacen en papel volant\u00edn y  con una t\u00e9cnica de recorte se van haciendo distintas decoraciones en el  papel. Es una artesan\u00eda muy tradicional all\u00e1 y es com\u00fan ver las calles  decoradas con estas guirnaldas. Hay con motivos que van desde la Virgen  de Guadalupe hasta para la fiesta quincea\u00f1era.<\/p>\n<p>Despu\u00e9s empec\u00e9 a ver en varias partes los banderines que son con  triangulos invertidos, con distintos g\u00e9neros de colores, floreados,  puntitos, etc&#8230; Encuentro que no hay nada m\u00e1s lindo para alegrar un  espacio y darle un toque veraniego y festivo todo el a\u00f1o. Les dejo algunas fotos de distintos lugares ambientados con los dos tipos de banderines.<\/p>\n<p>Si quieren comprar, en la revista M\u00e1s Decoraci\u00f3n sali\u00f3 el dato de Magdalena Cousi\u00f1o (magcousino@gmail.com). Si quieren los mexicanos, yo los compr\u00e9 en <a href=\"http:\/\/www.casabonampak.com\/\">www.casabonampak.com<\/a>\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-421 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/mexico_color_banners-smallcopy\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/mexico_color_banners-smallcopy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.acclaro.com\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/mexico_color_banners-smallcopy-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/mexico_color_banners-smallcopy-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/mexico_color_banners-smallcopy-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/mexico_color_banners-smallcopy-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/dscn1529\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/dscn15291-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: Paumes\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/dscn15291-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/dscn15291-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/dscn15291-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/dscn15291-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/fotobanderinesenhabitacioninfantil\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fotobanderinesenhabitacioninfantil-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.decocasa.com.ar\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fotobanderinesenhabitacioninfantil-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fotobanderinesenhabitacioninfantil-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fotobanderinesenhabitacioninfantil-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fotobanderinesenhabitacioninfantil-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/fiesta-toma2-78\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fiesta-toma2-781-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fiesta-toma2-781-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fiesta-toma2-781-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fiesta-toma2-781-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/fiesta-toma2-781-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/decoimg_0729b\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/decoimg_0729b2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.casamientofeliz.com\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/decoimg_0729b2-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/decoimg_0729b2-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/decoimg_0729b2-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/decoimg_0729b2-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/6a00d83501265b53ef01310f804469970c-800wi\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/6a00d83501265b53ef01310f804469970c-800wi-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.minordetails.typepad.com\/\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/6a00d83501265b53ef01310f804469970c-800wi-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/6a00d83501265b53ef01310f804469970c-800wi-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/6a00d83501265b53ef01310f804469970c-800wi-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/casabonam_2141_5853229-2\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/casabonam_2141_58532291-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.casabonampak.com\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/casabonam_2141_58532291-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/casabonam_2141_58532291-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/depto51.cl\/blog\/2011\/03\/08\/banderines-2\/il_fullxfull-64898200\/'><img width=\"150\" height=\"150\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/il_fullxfull-64898200-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"v\u00eda: www.etsy.com\" loading=\"lazy\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/il_fullxfull-64898200-150x150.jpg 150w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/il_fullxfull-64898200-306x306.jpg 306w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/il_fullxfull-64898200-225x225.jpg 225w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2011\/03\/il_fullxfull-64898200-145x145.jpg 145w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los primeros banderines con los que me obsesion\u00e9 fueron con los de papel picado mexicanos. Estos banderines se hacen en papel volant\u00edn y con una t\u00e9cnica de recorte se van haciendo distintas decoraciones en el papel. Es una artesan\u00eda muy tradicional all\u00e1 y es com\u00fan ver las calles decoradas con estas guirnaldas. Hay con motivos&#8230;<\/p>\n","protected":false},"author":2,"featured_media":424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[35,41,51,61],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/421"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/424"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}