

{"id":28052,"date":"2015-01-22T09:29:29","date_gmt":"2015-01-22T13:29:29","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=28052"},"modified":"2018-01-10T16:16:57","modified_gmt":"2018-01-10T20:16:57","slug":"mi-escritorio-felipe-rubilar","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2015\/01\/22\/mi-escritorio-felipe-rubilar\/","title":{"rendered":"Mi Escritorio: Felipe Rubilar"},"content":{"rendered":"<p>Nos encanta conocer nuevos lugares de trabajo, por eso estamos felices de esta colaboraci\u00f3n de Felipe Rubilar, fan\u00e1tico de los edificios y con lindos chiches en su mesa como cuadernos, libretas y hasta dulces.<\/p>\n<p>Recuerda que esta secci\u00f3n es abierta al p\u00fablico. Si quieres enviar tu escritorio env\u00edanos un mail a contacto@depto51.cl<\/p>\n<p><strong>Vitrinea en <a href=\"http:\/\/www.depto51.cl\/catalogo\/libreria\" target=\"_blank\">La Librer\u00eda<\/a> de nuestra tienda \ud83d\ude42 <\/strong><\/p>\n<p><a href=\"http:\/\/www.depto51.cl\/catalogo\/libreria\"><img loading=\"lazy\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163244.jpg\" alt=\"20141228_163244\" width=\"600\" height=\"338\" class=\"alignnone size-full wp-image-28053\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163244.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163244-500x281.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Dinos tu nombre y en qu\u00e9 trabajas:<\/strong><br \/>\nMi nombre es Felipe Rubilar, soy ingeniero civil y trabajo en una consultora dise\u00f1ando edificios de hormig\u00f3n armado.<\/p>\n<p><strong>\u00bfC\u00f3mo armaste tu escritorio?<\/strong><br \/>\nArm\u00e9 mi escritorio cuando me fui a vivir solo. El mueble lo compr\u00e9 en HOMY y las cosas las he ido recolectando de a poco. Lo dispuse frente a la ventana porque as\u00ed recibo luz durante todo el d\u00eda.<\/p>\n<p><a href=\"http:\/\/www.depto51.cl\/catalogo\/libreria\"><img loading=\"lazy\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163734.jpg\" alt=\"20141228_163734\" width=\"600\" height=\"338\" class=\"alignnone size-full wp-image-28054\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163734.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/20141228_163734-500x281.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.depto51.cl\/catalogo\/libreria\"><img loading=\"lazy\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/foto.jpg\" alt=\"foto\" width=\"599\" height=\"343\" class=\"alignnone size-full wp-image-28055\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/foto.jpg 599w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/foto-500x286.jpg 500w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/a><br \/>\n \u2028<br \/>\n<strong>\u00bfCu\u00e1les son tus objetos favoritos y por qu\u00e9?<\/strong><br \/>\nMe gustan mucho los edificios y por eso me traje una r\u00e9plica de la Willis Tower de Lego en un viaje que hice hace dos a\u00f1os. El cuadro es de \u00ab<a href=\"http:\/\/depto51.cl\/producto\/1817\/diario-de-un-solo\" target=\"_blank\">Diario de un solo<\/a>\u00bb y se lo compr\u00e9 a la <a href=\"https:\/\/depto51.cl\/blog\/2014\/08\/07\/mi-escritorio-catalina-bu\/\" target=\"_blank\">Catalina Bu<\/a>. \u00abLa noche es joven\u00bb me acompa\u00f1a cuando me quedo trasnochando, lo cual hago bien seguido.<br \/>\nNo pueden faltar sobre el escritorio libretas y un block de color amarillo. Lo usaba en la universidad y vez que lo veo compro alguno, ya que son escasos. Mi \u00faltima adquisici\u00f3n fue un frasco con tapa de ciervo que compr\u00e9 en la feria navide\u00f1a de \u00d1u\u00f1oa. Le dan sabor y color al escritorio.<\/p>\n<p><strong>Termina la oraci\u00f3n: Mi escritorio del computador es\u2026<\/strong> un recordatorio que estoy atrasado en lecturas varias y cosas por hacer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos encanta conocer nuevos lugares de trabajo, por eso estamos felices de esta colaboraci\u00f3n de Felipe Rubilar, fan\u00e1tico de los edificios y con lindos chiches en su mesa como cuadernos, libretas y hasta dulces. Recuerda que esta secci\u00f3n es abierta al p\u00fablico. Si quieres enviar tu escritorio env\u00edanos un mail a contacto@depto51.cl Vitrinea en La&#8230;<\/p>\n","protected":false},"author":1,"featured_media":28056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,567],"tags":[873,729,491],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/28052"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=28052"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/28052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/28056"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=28052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=28052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=28052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}