

{"id":27950,"date":"2016-01-05T11:01:22","date_gmt":"2016-01-05T15:01:22","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=27950"},"modified":"2018-03-09T10:10:48","modified_gmt":"2018-03-09T14:10:48","slug":"5-formas-pernas-de-mostrar-tus-fotos-de-matrimonio","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2016\/01\/05\/5-formas-pernas-de-mostrar-tus-fotos-de-matrimonio\/","title":{"rendered":"5 formas no pernas de mostrar tus fotos de matrimonio"},"content":{"rendered":"<p>Muchas veces no sabemos que hacer con las fotos que tomamos en el matrimonio. Porque ponerlo dentro de la casa, puede verse muy autoreferente y un poco perno, pero si le damos un estilo distinto, se puede lograr una buena idea de decoraci\u00f3n.<\/p>\n<p>En el blog <a href=\"http:\/\/www.brit.co\/diy-wedding-photo-home-decor\/\" target=\"_blank\">Brit+ Co<\/a> (que amamos) crearon cinco maneras divertidas que poner las fotos de tu matrimonio en la casa, hay formas muy originales, como banderines, magnetos o para adornar un regalo. Mira las fotos abajo e insp\u00edrate con este proyecto para el fin de semana.<\/p>\n<p><strong>Vitrinea en nuestra secci\u00f3n <a href=\"http:\/\/depto51.cl\/catalogo\/regalos-novios\" target=\"_blank\">Regalos Novios<\/a> \ud83d\ude42<br \/>\n<\/strong><\/p>\n<p>1.Banderines con estilo y<a href=\"http:\/\/www.depto51.cl\/buscar?where=PRODUCTOS&amp;pursuit=washi+tape\" target=\"_blank\"> washi tape<\/a><br \/>\n<a href=\"http:\/\/www.brit.co\/diy-wedding-photo-home-decor\/\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-27951\" alt=\"1-Garland-1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/1-Garland-1.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/1-Garland-1.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/1-Garland-1-500x333.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>2. Prueba con cuadros de diferentes tama\u00f1os, dej\u00e1ndolos en tu pared de forma divertida.<br \/>\n<a href=\"http:\/\/www.brit.co\/diy-wedding-photo-home-decor\/\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-27952\" alt=\"2-Wall-1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-1.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-1.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-1-500x333.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>3. Tambi\u00e9n puedes dejarlos rectos, pero con una forma creativa.<br \/>\n<a href=\"http:\/\/www.brit.co\/diy-wedding-photo-home-decor\/\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-27953\" alt=\"2-Wall-3\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-3.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-3.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/2-Wall-3-500x333.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>4. Qu\u00e9 mejor que el amor y las flores. Haz de tus fotos un lindo florero.<br \/>\n<a href=\"http:\/\/www.brit.co\/diy-wedding-photo-home-decor\/\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-27954\" alt=\"3-Vase-1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/3-Vase-1.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/3-Vase-1.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/3-Vase-1-500x333.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>5. Cada d\u00eda al desayuno, podr\u00e1s mirar las fotos de tu d\u00eda favorito si los conviertes en unos magnetos.<br \/>\n<img loading=\"lazy\" class=\"alignleft size-large wp-image-27962\" alt=\"5-Magnets-1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/5-Magnets-1-1024x682.jpg\" width=\"1024\" height=\"682\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/5-Magnets-1-1024x682.jpg 1024w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/5-Magnets-1-500x333.jpg 500w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2015\/01\/5-Magnets-1.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchas veces no sabemos que hacer con las fotos que tomamos en el matrimonio. Porque ponerlo dentro de la casa, puede verse muy autoreferente y un poco perno, pero si le damos un estilo distinto, se puede lograr una buena idea de decoraci\u00f3n. En el blog Brit+ Co (que amamos) crearon cinco maneras divertidas que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[479,35,461,866],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/27950"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=27950"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/27950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/27951"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=27950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=27950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=27950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}