

{"id":17214,"date":"2013-12-13T11:11:45","date_gmt":"2013-12-13T15:11:45","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=17214"},"modified":"2018-03-06T12:04:49","modified_gmt":"2018-03-06T16:04:49","slug":"un-departamiento-en-ukrania","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2013\/12\/13\/un-departamiento-en-ukrania\/","title":{"rendered":"Un departamento en Ukrania"},"content":{"rendered":"<p>Qu\u00e9 me dicen de este departamento en Kiev (Ukrania) dise\u00f1ado por Slava Balbek. \u00bfNo es genial? Un sof\u00e1 divide el alargado estar en dos partes. Lo curioso es que es un sill\u00f3n que tiene la posibilidad de sentarse mirando hacia ambos lados. \u00a1Ingenioso!<\/p>\n<p class=\"aligncenter size-full wp-image-17215\"><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-49.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17215\" alt=\"NewImage (49)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-49.png\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-49.png 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-49-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-47.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17217\" alt=\"NewImage (47)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-47.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-47.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-47-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-46.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17218\" alt=\"NewImage (46)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-46.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-46.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-46-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a>El ba\u00f1o es muy especial. Un cubo de marmol hace las veces de ducha. Le da una escala especial al ba\u00f1o, \u00bfno?\u00a0<a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-45.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17219\" alt=\"NewImage (45)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-45.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-45.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-45-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-44.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17220\" alt=\"NewImage (44)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-44.png\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-44.png 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-44-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-43.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17221\" alt=\"NewImage (43)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-43.png\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-43.png 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-43-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Una mesa con madera reciclada combina perfectamente con sillas escandinavas refinadas. Me gusta mucho esta combinaci\u00f3n de estilos.<\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-42.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17222\" alt=\"NewImage (42)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-42.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-42.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-42-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-41.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17223\" alt=\"NewImage (41)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-41.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-41.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-41-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-40.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17224\" alt=\"NewImage (40)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-40.png\" width=\"533\" height=\"800\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-40.png 533w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-40-333x500.png 333w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-38.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17225\" alt=\"NewImage (38)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-38.png\" width=\"600\" height=\"400\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-38.png 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-38-500x333.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a> <a href=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-37.png\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17226\" alt=\"NewImage (37)\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-37.png\" width=\"600\" height=\"339\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-37.png 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/12\/NewImage-37-500x282.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>V\u00eda <a href=\"http:\/\/www.behance.net\/gallery\/lipinka-apartment\/12281117\" target=\"_blank\">Behance<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 me dicen de este departamento en Kiev (Ukrania) dise\u00f1ado por Slava Balbek. \u00bfNo es genial? Un sof\u00e1 divide el alargado estar en dos partes. Lo curioso es que es un sill\u00f3n que tiene la posibilidad de sentarse mirando hacia ambos lados. \u00a1Ingenioso! El ba\u00f1o es muy especial. Un cubo de marmol hace las veces&#8230;<\/p>\n","protected":false},"author":12,"featured_media":17249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[20],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/17214"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=17214"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/17214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/17249"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=17214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=17214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=17214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}