

{"id":10952,"date":"2013-01-15T08:28:37","date_gmt":"2013-01-15T12:28:37","guid":{"rendered":"https:\/\/depto51.cl\/blog\/?p=10952"},"modified":"2013-01-15T08:28:37","modified_gmt":"2013-01-15T12:28:37","slug":"casitas-de-muneca","status":"publish","type":"post","link":"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/","title":{"rendered":"Casitas de Mu\u00f1eca"},"content":{"rendered":"<p>Para las dise\u00f1adoras de la firma polaca <a href=\"http:\/\/www.miniio.com\/\">Miniio<\/a> tener s\u00f3lo hijos hombres no fue un impedimento para volver a jugar con mu\u00f1ecas.\u00a0Es por eso que crearon una nueva versi\u00f3n de la cl\u00e1sica casita de mu\u00f1ecas que en los \u00faltimos a\u00f1os parec\u00eda destinada a ser de pl\u00e1stico.\u00a0Estas modernas mini casas son impresionantemente detallistas y\u00a0100% sustentables: cada pieza est\u00e1 elaborada a mano con madera, metal, piedra y algunos otros materiales no t\u00f3xicos. La terminaci\u00f3n final se hace con cera de abejas, imposible m\u00e1s natural.\u00a0Su tama\u00f1o es 6 veces m\u00e1s peque\u00f1o que una casa real, ideales para cualquier mu\u00f1eca de 30 cm o menos. Qu\u00e9 ganas de medir un poco menos para vivir en una de ellas!<\/p>\n<p>En el sitio web de <a href=\"http:\/\/www.miniio.com\/\">Miniio<\/a> pueden ver los distintos modelos disponibles.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/klimczak-drozdowska-saganowski-miniio-3\/\" rel=\"attachment wp-att-10989\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10989\" title=\"klimczak-drozdowska-saganowski-miniio-3\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/klimczak-drozdowska-saganowski-miniio-3.jpg\" alt=\"\" width=\"900\" height=\"592\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/klimczak-drozdowska-saganowski-miniio-3.jpg 900w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/klimczak-drozdowska-saganowski-miniio-3-500x328.jpg 500w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/miniio-1\/\" rel=\"attachment wp-att-10990\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10990\" title=\"miniio-1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/miniio-1.png\" alt=\"\" width=\"660\" height=\"747\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/miniio-1.png 660w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/miniio-1-441x500.png 441w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/miniio1\/\" rel=\"attachment wp-att-10993\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10993\" title=\"Miniio1\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/Miniio1.jpg\" alt=\"\" width=\"720\" height=\"393\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/Miniio1.jpg 720w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/Miniio1-500x272.jpg 500w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/m4\/\" rel=\"attachment wp-att-10995\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10995\" title=\"m4\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/m4.jpg\" alt=\"\" width=\"960\" height=\"764\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/m4.jpg 960w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/m4-500x397.jpg 500w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/depto51.cl\/blog\/2013\/01\/15\/casitas-de-muneca\/casa_madera_barbie4-600x390\/\" rel=\"attachment wp-att-10997\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-10997\" title=\"casa_madera_Barbie4-600x390\" src=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/casa_madera_Barbie4-600x390.jpg\" alt=\"\" width=\"600\" height=\"390\" srcset=\"https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/casa_madera_Barbie4-600x390.jpg 600w, https:\/\/depto51.cl\/blog\/wp-content\/uploads\/2013\/01\/casa_madera_Barbie4-600x390-500x325.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para las dise\u00f1adoras de la firma polaca Miniio tener s\u00f3lo hijos hombres no fue un impedimento para volver a jugar con mu\u00f1ecas.\u00a0Es por eso que crearon una nueva versi\u00f3n de la cl\u00e1sica casita de mu\u00f1ecas que en los \u00faltimos a\u00f1os parec\u00eda destinada a ser de pl\u00e1stico.\u00a0Estas modernas mini casas son impresionantemente detallistas y\u00a0100% sustentables: cada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[51],"acf":[],"_links":{"self":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/10952"}],"collection":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/comments?post=10952"}],"version-history":[{"count":0,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/posts\/10952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media\/10996"}],"wp:attachment":[{"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/media?parent=10952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/categories?post=10952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/depto51.cl\/blog\/wp-json\/wp\/v2\/tags?post=10952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}